{"id":8511972,"date":"2023-06-07T10:30:00","date_gmt":"2023-06-07T10:30:00","guid":{"rendered":"https:\/\/www.openathens.net\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/"},"modified":"2026-08-12T15:43:18","modified_gmt":"2026-08-12T15:43:18","slug":"por-que-openathens-compass-es-la-solucion-completa-que-necesitas","status":"publish","type":"post","link":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/","title":{"rendered":"Por qu\u00e9 OpenAthens Compass es la soluci\u00f3n completa que necesitas"},"content":{"rendered":"<div class=\"container\">\n<h2 class=\"wp-block-heading\" id=\"\"><strong>La soluci\u00f3n completa OpenAthens Compass ayuda a los bibliotecarios a conectarse con miles de editoriales y a preparar su sistema de autenticaci\u00f3n para el futuro. La idea es sencilla: ofrecemos una \u00fanica herramienta que proporciona un acceso f\u00e1cil a los recursos y cuenta con soporte integral. Una herramienta que facilita el trabajo de los bibliotecarios al eliminar preocupaciones, independientemente de c\u00f3mo evolucione el sector. <a href=\"https:\/\/www.openathens.net\/es\/bibliotecarios\/estoy-utilizando-un-proxy-por-que-necesito-openathens\/\">Nuestra soluci\u00f3n completa<\/a> prepara su estrategia de autenticaci\u00f3n para el futuro.<\/strong><\/h2>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">Una herramienta sin complicaciones puede sonar demasiado buena para ser verdad. Sin embargo, la soluci\u00f3n completa es una realidad, pero \u00bfpor qu\u00e9 es la respuesta a la mayor\u00eda de los retos relacionados con la autenticaci\u00f3n?<\/p>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">La misi\u00f3n de OpenAthens es conectar a las personas con la informaci\u00f3n, por lo que nuestra soluci\u00f3n completa utiliza diferentes tecnolog\u00edas para conectar las bibliotecas con los recursos, independientemente del punto en el que los usuarios inicien su recorrido.<\/p>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">Aunque <a href=\"https:\/\/youtu.be\/RbJVNB3tRx0\" target=\"_blank\" rel=\"noreferrer noopener\">el sector contin\u00faa avanzando hacia un futuro basado en el acceso federado seguro, todav\u00eda hay organizaciones que no est\u00e1n preparadas para dar ese paso, y OpenAthens quiere eliminar las barreras al acceso a la informaci\u00f3n, aunque ello implique seguir dando soporte a tecnolog\u00edas menos modernas.<\/a><\/p>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">Somos conscientes de que, aunque las grandes plataformas admiten acceso federado, todav\u00eda existen numerosos recursos bibliotecarios publicados por organizaciones mucho m\u00e1s peque\u00f1as que no disponen de los recursos ni de la necesidad de implantar este tipo de acceso. Por eso, s\u00ed: el proxy sigue siendo una soluci\u00f3n importante en nuestro \u00e1mbito y nosotros te ofrecemos soporte para ella.<\/p>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">Lo que tambi\u00e9n es seguro es que, cuando el proxy vaya perdiendo relevancia como m\u00e9todo de autenticaci\u00f3n, los clientes de <a href=\"https:\/\/youtu.be\/2bGmS7dZ6j0\" target=\"_blank\" rel=\"noreferrer noopener\">OpenAthens seguir\u00e1n protegidos gracias a la autenticaci\u00f3n federada<\/a>. OpenAthens Compass no solo admite autenticaci\u00f3n federada y de inicio de sesi\u00f3n \u00fanico basada en SAML, sino que adem\u00e1s dispone de su propia federaci\u00f3n.<\/p>\n<\/div><div class=\"container\">\n<h3 class=\"wp-block-heading\" id=\"la-soluci%c3%b3n-completa\">La soluci\u00f3n completa<\/h3>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">La soluci\u00f3n completa OpenAthens Compass es compatible tanto con el proxy gestionado como con la autenticaci\u00f3n federada, y elimina las barreras al conocimiento mediante un producto pensado para quienes quieren anticiparse al futuro. Al ser compatible con distintas tecnolog\u00edas, OpenAthens proporciona una soluci\u00f3n preparada para el futuro en la que puedes confiar.<\/p>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">OpenAthens es una organizaci\u00f3n sin \u00e1nimo de lucro, propiedad del sector y al servicio del sector. Dispone de su propia federaci\u00f3n: una comunidad a la que pueden unirse organizaciones, bibliotecas y editoriales para establecer relaciones entre s\u00ed. Esto facilita la ampliaci\u00f3n de la identidad federada, de modo que cientos de miles de organizaciones puedan comunicarse con cientos de sitios diferentes sin necesidad de realizar una compleja configuraci\u00f3n t\u00e9cnica.<\/p>\n<\/div><div class=\"container\">\n<h3 class=\"wp-block-heading\" id=\"servicio-gestionado\">Servicio gestionado<\/h3>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">\u00bfY si en alg\u00fan momento necesitas ayuda t\u00e9cnica? Con un \u00edndice de satisfacci\u00f3n del cliente del 92 %, OpenAthens destaca por la calidad de su experiencia de cliente. Se trata de un servicio totalmente gestionado, lo que significa que expertos especializados te acompa\u00f1an durante el proceso de incorporaci\u00f3n y se encargan de resolver cualquier incidencia que pueda surgir una vez que te conviertas en cliente.<\/p>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">OpenAthens Compass proporciona un proxy completamente gestionado y una direcci\u00f3n IP. Adem\u00e1s, se encarga de la configuraci\u00f3n de los sitios proxy, por lo que no necesitas invertir tiempo ni recursos adicionales para mantener el producto funcionando correctamente.<\/p>\n<\/div><div class=\"container\">\n<h3 class=\"wp-block-heading\" id=\"preparado-para-el-futuro\">Preparado para el futuro<\/h3>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">La web es cada vez m\u00e1s compleja; las plataformas de las editoriales tambi\u00e9n lo son, por lo que el tiempo necesario para configurar productos proxy capaces de reescribir contenido de forma fiable aumenta debido a esa complejidad. Por ello, el sector est\u00e1 impulsando t\u00e9cnicamente el acceso federado para simplificar el futuro de la autenticaci\u00f3n.<\/p>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">La soluci\u00f3n completa OpenAthens Compass responde a las necesidades y preocupaciones del sector, tanto si las organizaciones necesitan acceso mediante IP, acceso federado o gestionar directamente un proxy.<\/p>\n<\/div><div class=\"container\">\n<p class=\"core-paragraph wp-block-paragraph\">La pandemia puso de manifiesto la necesidad de disponer de acceso remoto desde fuera de las instalaciones, sin depender exclusivamente del reconocimiento por direcci\u00f3n IP. Esto permiti\u00f3 demostrar el valor de OpenAthens Compass como una soluci\u00f3n preparada para el futuro, dise\u00f1ada para garantizar un acceso sencillo ayer, hoy y en los pr\u00f3ximos a\u00f1os.<\/p>\n<\/div><section class=\"comparison-table\">\n\t<div class=\"container\">\n\t\t<h2 class=\"comparison-table__title\" id=\"tipos-de-m%c3%a9todos-de-autenticaci%c3%b3n\">Tipos de m\u00e9todos de autenticaci\u00f3n<\/h2>\n\t\t<div class=\"comparison-table__wrapper\">\n\t\t\t<table class=\"comparison-table__table\">\n\t\t\t\t\t\t\t\t<tbody class=\"comparison-table__body\">\n\t\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th scope=\"row\" class=\"comparison-table__header comparison-table__header--feature\">Reconocimiento por IP<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"comparison-table__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\talt='A tick indicating this feature is available'\n\t\t\t\t\t\t\t\t\t\t\tsrc='\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/tick.svg'\n\t\t\t\t\t\t\t\t\t\t\tclass='comparison-table__icon__image'\n\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"comparison-table__body\"><ul>\n<li>Compatible con la mayor\u00eda de las editoriales<\/li>\n<li>F\u00e1cil de configurar\u200b<\/li>\n<li>Funciona sin interrupciones dentro del campus<\/li>\n<\/ul>\n<\/span>\n\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"comparison-table__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\talt='A cross indicating this feature is unavailable'\n\t\t\t\t\t\t\t\t\t\t\tsrc='\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/cross.svg'\n\t\t\t\t\t\t\t\t\t\t\tclass='comparison-table__icon__image'\n\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"comparison-table__body\"><ul>\n<li>No funciona fuera del campus\u200b<\/li>\n<li>No es seguro. No puedes garantizar qui\u00e9n accede desde un rango de direcciones IP autorizado<\/li>\n<li>No permite la personalizaci\u00f3n en los sitios web de las editoriales<\/li>\n<\/ul>\n<\/span>\n\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th scope=\"row\" class=\"comparison-table__header comparison-table__header--feature\">Proxy alojado<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"comparison-table__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\talt='A tick indicating this feature is available'\n\t\t\t\t\t\t\t\t\t\t\tsrc='\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/tick.svg'\n\t\t\t\t\t\t\t\t\t\t\tclass='comparison-table__icon__image'\n\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"comparison-table__body\"><ul>\n<li>Permite el acceso remoto a recursos restringidos por IP<\/li>\n<li>Funciona con la mayor\u00eda de las editoriales<\/li>\n<li>Coste relativamente bajo<\/li>\n<\/ul>\n<\/span>\n\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"comparison-table__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\talt='A cross indicating this feature is unavailable'\n\t\t\t\t\t\t\t\t\t\t\tsrc='\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/cross.svg'\n\t\t\t\t\t\t\t\t\t\t\tclass='comparison-table__icon__image'\n\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"comparison-table__body\"><ul>\n<li>Puede resultar fr\u00e1gil. Puede dejar de funcionar si las editoriales realizan cambios en sus sitios web<\/li>\n<li>Requiere configuraci\u00f3n por parte de cada biblioteca que lo utilice<\/li>\n<li>No permite la personalizaci\u00f3n en los sitios web de las editoriales<\/li>\n<\/ul>\n<\/span>\n\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th scope=\"row\" class=\"comparison-table__header comparison-table__header--feature\">Proxy gestionado<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"comparison-table__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\talt='A tick indicating this feature is available'\n\t\t\t\t\t\t\t\t\t\t\tsrc='\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/tick.svg'\n\t\t\t\t\t\t\t\t\t\t\tclass='comparison-table__icon__image'\n\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"comparison-table__body\"><ul>\n<li>Permite el acceso remoto a recursos restringidos por IP<\/li>\n<li>Funciona con la mayor\u00eda de las editoriales que no admiten acceso federado<\/li>\n<li>No requiere configuraci\u00f3n por parte del bibliotecario<\/li>\n<\/ul>\n<\/span>\n\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"comparison-table__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\talt='A cross indicating this feature is unavailable'\n\t\t\t\t\t\t\t\t\t\t\tsrc='\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/cross.svg'\n\t\t\t\t\t\t\t\t\t\t\tclass='comparison-table__icon__image'\n\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"comparison-table__body\"><ul>\n<li>Puede resultar fr\u00e1gil. Puede dejar de funcionar si las editoriales realizan cambios en sus sitios web<\/li>\n<li>No es compatible con todas las editoriales. Requiere configuraci\u00f3n por parte de OpenAthens si el recurso todav\u00eda no est\u00e1 disponible mediante proxy<\/li>\n<li>No permite la personalizaci\u00f3n en los sitios web de las editoriales<\/li>\n<\/ul>\n<\/span>\n\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th scope=\"row\" class=\"comparison-table__header comparison-table__header--feature\">Autenticaci\u00f3n federada<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"comparison-table__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\talt='A tick indicating this feature is available'\n\t\t\t\t\t\t\t\t\t\t\tsrc='\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/tick.svg'\n\t\t\t\t\t\t\t\t\t\t\tclass='comparison-table__icon__image'\n\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"comparison-table__body\"><ul>\n<li>Est\u00e1ndar del sector y ampliamente utilizado fuera del \u00e1mbito bibliotecario<\/li>\n<li>T\u00fa decides qu\u00e9 informaci\u00f3n deseas compartir<\/li>\n<li>Soluci\u00f3n basada en la nube y preparada para el futuro<\/li>\n<li>Segura y estable<\/li>\n<\/ul>\n<\/span>\n\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"comparison-table__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\talt='A cross indicating this feature is unavailable'\n\t\t\t\t\t\t\t\t\t\t\tsrc='\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/cross.svg'\n\t\t\t\t\t\t\t\t\t\t\tclass='comparison-table__icon__image'\n\t\t\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"comparison-table__body\"><ul>\n<li>Puede que el proxy sea m\u00e1s sencillo de configurar. Sin embargo, OpenAthens configura SAML por ti<\/li>\n<li>No todos los proveedores admiten acceso federado<\/li>\n<\/ul>\n<\/span>\n\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t<\/tbody>\n\t\t\t<\/table>\n\t\t<\/div>\n\t\t<div class=\"comparison-table__controls\">\n\t\t\t<button class=\"comparison-table__prev cta-button--secondary\">\n\t\t\t\t<img\n\t\t\t\t\tclass=\"comparison-table__arrow--prev\"\n\t\t\t\t\tsrc=\"https:\/\/www.openathens.net\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/system--arrow-right--dark-pink.svg\"\n\t\t\t\t\talt=\"Previous arrow\"\n\t\t\t\t\/>\n\t\t\t\t<span class=\"visually-hidden\">Previous column<\/span>\n\t\t\t<\/button>\n\t\t\t\n\t\t\t<button class=\"comparison-table__next cta-button cta-button--secondary\">\n\t\t\t\t<img\n\t\t\t\t\tclass=\"comparison-table__arrow--next\"\n\t\t\t\t\tsrc=\"https:\/\/www.openathens.net\/app\/themes\/sage\/resources\/assets\/images\/rebrand_svgs\/system--arrow-right--dark-pink.svg\"\n\t\t\t\t\talt=\"Next arrow\"\n\t\t\t\t\/>\n\t\t\t\t<span class=\"visually-hidden\">Next column<\/span>\n\t\t\t<\/button>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n<div class=\"block-wrapper block-spacing--top\">\n\t<section class=\"tout-reversible tout-reversible bg-jade-dark tout-reversible--image-right\">\n\t<div class=\"tout-reversible__container\">\n\t\t<div class='tout__image--wrapper square-image'>\n\t\t\t\t<picture\n\tclass=\"image   \"\n\t\t\t\t>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-150x150.jpg\"\n\t\t\tmedia=\"(max-width: 150px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-150x150.jpg.webp\"\n\t\t\tmedia=\"(max-width: 150px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-300x200.jpg\"\n\t\t\tmedia=\"(max-width: 300px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-300x200.jpg\"\n\t\t\tmedia=\"(max-width: 300px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-300x200.jpg.webp\"\n\t\t\tmedia=\"(max-width: 300px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-300x200.jpg.webp\"\n\t\t\tmedia=\"(max-width: 300px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-450x300.jpg\"\n\t\t\tmedia=\"(max-width: 450px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-450x300.jpg.webp\"\n\t\t\tmedia=\"(max-width: 450px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-768x512.jpg\"\n\t\t\tmedia=\"(max-width: 768px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-768x512.jpg.webp\"\n\t\t\tmedia=\"(max-width: 768px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1024x683.jpg\"\n\t\t\tmedia=\"(max-width: 1024px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1024x683.jpg.webp\"\n\t\t\tmedia=\"(max-width: 1024px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1200x800.jpg\"\n\t\t\tmedia=\"(max-width: 1200px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1200x800.jpg.webp\"\n\t\t\tmedia=\"(max-width: 1200px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1350x900.jpg\"\n\t\t\tmedia=\"(max-width: 1350px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1350x900.jpg.webp\"\n\t\t\tmedia=\"(max-width: 1350px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1536x1024.jpg\"\n\t\t\tmedia=\"(max-width: 1536px)\"\n\t\t\/>\n\t\t\t<source\n\t\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1536x1024.jpg.webp\"\n\t\t\tmedia=\"(max-width: 1536px)\"\n\t\t\/>\n\t\t<img\n\t\tclass=\" tout__image--square \"\n\t\tsrc=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1200x800.jpg\"\n\t\tsrcset=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/02\/marvin-meyer-SYTO3xs06fU-unsplash-1-1200x800.jpg\" alt=\"Laptops on a table in college \"\n\t\/>\n<\/picture>\n\n\t\t<\/div>\n\n\t\t<article class='tout__text' aria-label=\"Article content for the post, '\u00bfQuieres saber m\u00e1s sobre la privacidad de los usuarios?'\">\n\t<h2 class='tout__title text-white' id=\"%c2%bfquieres-saber-m%c3%a1s-sobre-la-privacidad-de-los-usuarios\">\u00bfQuieres saber m\u00e1s sobre la privacidad de los usuarios?<\/h2>\n\t<div class='tout__body text-white'><p>\u00bfSab\u00edas que OpenAthens no divulga de forma predeterminada ninguna informaci\u00f3n de identificaci\u00f3n personal (PII)?<\/p>\n<p>Mira \u00abSeguridad y privacidad de los usuarios\u00bb, de nuestra serie de seminarios web Back to basics, para obtener m\u00e1s informaci\u00f3n sobre OpenAthens, las cookies, las contrase\u00f1as, la autenticaci\u00f3n y la autorizaci\u00f3n.<\/p>\n<p>Descubre todo lo que necesitas saber sobre la seguridad y la privacidad de los usuarios mediante una presentaci\u00f3n sencilla y f\u00e1cil de seguir de nuestro director de desarrollo de negocio, Kieran Prince.<\/p>\n<\/div>\n\t\t\t<a\n\t\t\t\t\t\t\t\t\thref=\"https:\/\/youtu.be\/2bGmS7dZ6j0\"\n\t\t\t\t\t\t\ttarget=\"_self\"\n\t\t\t\t\t\t\trel=\"\"\n\t\t\t\t\t\t\tclass='cta-button cta-button--primary cta-button--small'\n\t>\n\t\tVer nuestro seminario web sobre la privacidad de los usuarios\n\t<\/a>\n\t\t<\/article>\n\t<\/div>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La soluci\u00f3n completa OpenAthens Compass ayuda a los bibliotecarios a conectarse con miles de editoriales y a preparar su sistema de autenticaci\u00f3n para el futuro. La idea es sencilla: ofrecemos una \u00fanica herramienta que proporciona un acceso f\u00e1cil a los recursos y cuenta con soporte integral. Una herramienta que facilita el trabajo de los bibliotecarios &hellip;<\/p>\n","protected":false},"author":32,"featured_media":8486633,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[98],"audience":[127,194],"content-type":[129],"topic":[147,153,172],"class_list":["post-8511972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","content-type-blog-es","topic-acceso-federado","topic-experiencia-de-usuario","topic-proxy-gestionado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por qu\u00e9 OpenAthens Compass es la soluci\u00f3n completa que necesitas<\/title>\n<meta name=\"description\" content=\"IP frente a proxy gestionado frente a autenticaci\u00f3n federada: por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas\" \/>\n<meta property=\"og:description\" content=\"IP frente a proxy gestionado frente a autenticaci\u00f3n federada: por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/\" \/>\n<meta property=\"og:site_name\" content=\"OpenAthens\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-07T10:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T15:43:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/06\/pexels-buro-millennial-1438084-1-e1686207177831-1024x461.jpg\" \/>\n<meta name=\"author\" content=\"Candela Valle Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.openathens.net\/app\/uploads\/2023\/06\/pexels-buro-millennial-1438084-1-e1686207177831-1024x461.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Candela Valle Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/\"},\"author\":{\"name\":\"Candela Valle Silva\",\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/#\\\/schema\\\/person\\\/f0949892056f3a7806ab84161b292fe8\"},\"headline\":\"Por qu\u00e9 OpenAthens Compass es la soluci\u00f3n completa que necesitas\",\"datePublished\":\"2023-06-07T10:30:00+00:00\",\"dateModified\":\"2026-08-12T15:43:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/\"},\"wordCount\":739,\"publisher\":{\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.openathens.net\\\/app\\\/uploads\\\/2023\\\/06\\\/pexels-buro-millennial-1438084-1-e1686207177831.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/\",\"url\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/\",\"name\":\"Por qu\u00e9 OpenAthens Compass es la soluci\u00f3n completa que necesitas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.openathens.net\\\/app\\\/uploads\\\/2023\\\/06\\\/pexels-buro-millennial-1438084-1-e1686207177831.jpg\",\"datePublished\":\"2023-06-07T10:30:00+00:00\",\"dateModified\":\"2026-08-12T15:43:18+00:00\",\"description\":\"IP frente a proxy gestionado frente a autenticaci\u00f3n federada: por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/blog\\\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.openathens.net\\\/app\\\/uploads\\\/2023\\\/06\\\/pexels-buro-millennial-1438084-1-e1686207177831.jpg\",\"contentUrl\":\"https:\\\/\\\/www.openathens.net\\\/app\\\/uploads\\\/2023\\\/06\\\/pexels-buro-millennial-1438084-1-e1686207177831.jpg\",\"width\":1920,\"height\":1282,\"caption\":\"Group of people studying together around a laptop\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/\",\"name\":\"OpenAthens\",\"description\":\"Remote access made simple\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/#organization\",\"name\":\"OpenAthens\",\"url\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.openathens.net\\\/app\\\/uploads\\\/2022\\\/08\\\/OA_PRIMARY-LOGO_RGB_-BLUE.png\",\"contentUrl\":\"https:\\\/\\\/www.openathens.net\\\/app\\\/uploads\\\/2022\\\/08\\\/OA_PRIMARY-LOGO_RGB_-BLUE.png\",\"width\":500,\"height\":164,\"caption\":\"OpenAthens\"},\"image\":{\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/#\\\/schema\\\/person\\\/f0949892056f3a7806ab84161b292fe8\",\"name\":\"Candela Valle Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e80b45695631b3dc5b364f43f3a5d86f822b72010ae3a8299928eb6f3bd314bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e80b45695631b3dc5b364f43f3a5d86f822b72010ae3a8299928eb6f3bd314bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e80b45695631b3dc5b364f43f3a5d86f822b72010ae3a8299928eb6f3bd314bd?s=96&d=mm&r=g\",\"caption\":\"Candela Valle Silva\"},\"url\":\"https:\\\/\\\/www.openathens.net\\\/es\\\/author\\\/candelasilva\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 OpenAthens Compass es la soluci\u00f3n completa que necesitas","description":"IP frente a proxy gestionado frente a autenticaci\u00f3n federada: por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas","og_description":"IP frente a proxy gestionado frente a autenticaci\u00f3n federada: por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas","og_url":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/","og_site_name":"OpenAthens","article_published_time":"2023-06-07T10:30:00+00:00","article_modified_time":"2026-08-12T15:43:18+00:00","og_image":[{"url":"https:\/\/www.openathens.net\/app\/uploads\/2023\/06\/pexels-buro-millennial-1438084-1-e1686207177831-1024x461.jpg","type":"","width":"","height":""}],"author":"Candela Valle Silva","twitter_card":"summary_large_image","twitter_title":"Por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas","twitter_image":"https:\/\/www.openathens.net\/app\/uploads\/2023\/06\/pexels-buro-millennial-1438084-1-e1686207177831-1024x461.jpg","twitter_misc":{"Written by":"Candela Valle Silva","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/#article","isPartOf":{"@id":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/"},"author":{"name":"Candela Valle Silva","@id":"https:\/\/www.openathens.net\/es\/#\/schema\/person\/f0949892056f3a7806ab84161b292fe8"},"headline":"Por qu\u00e9 OpenAthens Compass es la soluci\u00f3n completa que necesitas","datePublished":"2023-06-07T10:30:00+00:00","dateModified":"2026-08-12T15:43:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/"},"wordCount":739,"publisher":{"@id":"https:\/\/www.openathens.net\/es\/#organization"},"image":{"@id":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.openathens.net\/app\/uploads\/2023\/06\/pexels-buro-millennial-1438084-1-e1686207177831.jpg","articleSection":["Sin categorizar"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/","url":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/","name":"Por qu\u00e9 OpenAthens Compass es la soluci\u00f3n completa que necesitas","isPartOf":{"@id":"https:\/\/www.openathens.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/#primaryimage"},"image":{"@id":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.openathens.net\/app\/uploads\/2023\/06\/pexels-buro-millennial-1438084-1-e1686207177831.jpg","datePublished":"2023-06-07T10:30:00+00:00","dateModified":"2026-08-12T15:43:18+00:00","description":"IP frente a proxy gestionado frente a autenticaci\u00f3n federada: por qu\u00e9 OpenAthens es la soluci\u00f3n completa que necesitas","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.openathens.net\/es\/blog\/por-que-openathens-compass-es-la-solucion-completa-que-necesitas\/#primaryimage","url":"https:\/\/www.openathens.net\/app\/uploads\/2023\/06\/pexels-buro-millennial-1438084-1-e1686207177831.jpg","contentUrl":"https:\/\/www.openathens.net\/app\/uploads\/2023\/06\/pexels-buro-millennial-1438084-1-e1686207177831.jpg","width":1920,"height":1282,"caption":"Group of people studying together around a laptop"},{"@type":"WebSite","@id":"https:\/\/www.openathens.net\/es\/#website","url":"https:\/\/www.openathens.net\/es\/","name":"OpenAthens","description":"Remote access made simple","publisher":{"@id":"https:\/\/www.openathens.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.openathens.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.openathens.net\/es\/#organization","name":"OpenAthens","url":"https:\/\/www.openathens.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.openathens.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.openathens.net\/app\/uploads\/2022\/08\/OA_PRIMARY-LOGO_RGB_-BLUE.png","contentUrl":"https:\/\/www.openathens.net\/app\/uploads\/2022\/08\/OA_PRIMARY-LOGO_RGB_-BLUE.png","width":500,"height":164,"caption":"OpenAthens"},"image":{"@id":"https:\/\/www.openathens.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.openathens.net\/es\/#\/schema\/person\/f0949892056f3a7806ab84161b292fe8","name":"Candela Valle Silva","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/e80b45695631b3dc5b364f43f3a5d86f822b72010ae3a8299928eb6f3bd314bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e80b45695631b3dc5b364f43f3a5d86f822b72010ae3a8299928eb6f3bd314bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e80b45695631b3dc5b364f43f3a5d86f822b72010ae3a8299928eb6f3bd314bd?s=96&d=mm&r=g","caption":"Candela Valle Silva"},"url":"https:\/\/www.openathens.net\/es\/author\/candelasilva\/"}]}},"_links":{"self":[{"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/posts\/8511972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/comments?post=8511972"}],"version-history":[{"count":3,"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/posts\/8511972\/revisions"}],"predecessor-version":[{"id":8511979,"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/posts\/8511972\/revisions\/8511979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/media\/8486633"}],"wp:attachment":[{"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/media?parent=8511972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/categories?post=8511972"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/audience?post=8511972"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/content-type?post=8511972"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.openathens.net\/es\/wp-json\/wp\/v2\/topic?post=8511972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}